{"id":22,"count":3,"description":"","link":"https:\/\/naturallyenglish.nl\/nl\/tag\/businessenglish\/","name":"BusinessEnglish","slug":"businessenglish","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/naturallyenglish.nl\/nl\/wp-json\/wp\/v2\/tags\/22"}],"collection":[{"href":"https:\/\/naturallyenglish.nl\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/naturallyenglish.nl\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/naturallyenglish.nl\/nl\/wp-json\/wp\/v2\/posts?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}